
{"id":9876,"date":"2011-10-24T18:40:55","date_gmt":"2011-10-24T21:40:55","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=9876"},"modified":"2011-10-24T18:40:55","modified_gmt":"2011-10-24T21:40:55","slug":"deputado-baiano-do-pr-pode-ser-cassado-apos-denuncia-da-veja","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/24\/deputado-baiano-do-pr-pode-ser-cassado-apos-denuncia-da-veja\/","title":{"rendered":"DEPUTADO BAIANO DO PR PODE SER CASSADO AP\u00d3S DENUNCIA DA VEJA"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.partidodarepublica.org.br\/partido\/Dep_joaoBacelar\/936-0009.JPG\" alt=\"\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Den\u00fancias da Veja podem derrubar o deputado Jo\u00e3o Carlos Bacelar<\/strong><\/em><\/p>\n<p>O deputado federal Jo\u00e3o Carlos Bacelar (PR-BA) est\u00e1 trancado a sete chaves ap\u00f3s a den\u00fancia publicada na revista Veja de que ele empregaria parentes do deputado estadual Nelson Leal (PSL) em seu gabinete. Em troca, garantiria emprego para dois parentes seus no gabinete do deputado Leal, numa esp\u00e9cie de permuta. A entrevista d\u00e1 conta ainda de que Bacelar direcionava emendas parlamentares para obras da empreiteira da fam\u00edlia, a Empresa Brasileira de Terraplanagem e Constru\u00e7\u00f5es (Embratec). O Pol\u00edtica Hoje tentou contato com Jo\u00e3o Carlos Bacelar, mas a assessoria de imprensa afirmou que ele n\u00e3o falar\u00e1 sobre o assunto. Tamb\u00e9m atrav\u00e9s da assessoria, o deputado garantiu ao jornal A Tarde que pediria a exonera\u00e7\u00e3o dos parentes que trabalham na Assembleia Legislativa. O presidente do Conselho de \u00c9tica da C\u00e2mara Federal, Jos\u00e9 Carlos Ara\u00fajo (PDT-BA), afirmou que n\u00e3o pode fazer nada at\u00e9 que seja solicitado por algum \u00f3rg\u00e3o ou parlamentar. \u201c<em>S\u00f3 posso tomar uma atitude se for provocado. Caso isso aconte\u00e7a, tenho que nomear um relator e dar andamento \u00e0s investiga\u00e7\u00f5es em 90 dias. A pena m\u00e1xima \u00e9 a cassa\u00e7\u00e3o, mas ele pode receber uma suspens\u00e3o. Tudo depende, na verdade, dos conselheiros\u201d,<\/em> explicou. Informa\u00e7\u00f5es do Pol\u00edtica Hoje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Den\u00fancias da Veja podem derrubar o deputado Jo\u00e3o Carlos Bacelar O deputado federal Jo\u00e3o Carlos Bacelar (PR-BA) est\u00e1 trancado a sete chaves ap\u00f3s a den\u00fancia publicada na revista Veja de que ele empregaria parentes do deputado estadual Nelson Leal (PSL) em seu gabinete. Em troca, garantiria emprego para dois parentes seus no gabinete do deputado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-9876","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1170,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=9876"}],"version-history":[{"count":4,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9876\/revisions"}],"predecessor-version":[{"id":9880,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9876\/revisions\/9880"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=9876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=9876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=9876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}