
{"id":9503,"date":"2011-10-10T19:45:06","date_gmt":"2011-10-10T22:45:06","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=9503"},"modified":"2011-10-10T19:46:02","modified_gmt":"2011-10-10T22:46:02","slug":"dilma-manda-cortar-ponto-de-grevistas-dos-correios-caixa-e-banco-do-brasil","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/10\/dilma-manda-cortar-ponto-de-grevistas-dos-correios-caixa-e-banco-do-brasil\/","title":{"rendered":"DILMA MANDA CORTAR PONTO DE GREVISTAS DOS CORREIOS, CAIXA E BANCO DO BRASIL"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/bahiapress.com.br\/wordpress\/wp-content\/uploads\/2010\/05\/greve.jpg\" alt=\"\" width=\"400\" \/><\/p>\n<p>Uma pr\u00e1tica raramente vista no governo do ex-presidente Luiz In\u00e1cio Lula da Silva (PT), mas presente na gest\u00e3o da mandat\u00e1ria brasileira Dilma Rousseff (PT), irritou sindicalistas. A necessidade de ajuste fiscal e o receio de uma escalada inflacion\u00e1ria levaram o Executivo a endurecer a pol\u00edtica de greves e atacar o &#8220;bolso dos grevistas&#8221; com corte de ponto.\u00a0Assim, a presidente Dilma Rousseff entende que pode evitar um efeito domin\u00f3. Ela n\u00e3o quer que as greves dos Correios e dos bancos sejam um est\u00edmulo para outras categorias que j\u00e1 reclamam por melhorias salariais.<\/p>\n<p>Agora, no 13\u00ba dia de greve dos bancos, o Pal\u00e1cio do Planalto repassou a ordem ao Minist\u00e9rio da Fazenda para que as dire\u00e7\u00f5es do Banco do Brasil e da Caixa Econ\u00f4mica Federal cortem o ponto dos grevistas. A ordem tamb\u00e9m \u00e9 pra ser adotada para os funcion\u00e1rios da Empresa Brasileira de Correios e Tel\u00e9grafos.<\/p>\n<p><strong><em>Dos Jornais<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pr\u00e1tica raramente vista no governo do ex-presidente Luiz In\u00e1cio Lula da Silva (PT), mas presente na gest\u00e3o da mandat\u00e1ria brasileira Dilma Rousseff (PT), irritou sindicalistas. A necessidade de ajuste fiscal e o receio de uma escalada inflacion\u00e1ria levaram o Executivo a endurecer a pol\u00edtica de greves e atacar o &#8220;bolso dos grevistas&#8221; com corte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-9503","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1188,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=9503"}],"version-history":[{"count":6,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9503\/revisions"}],"predecessor-version":[{"id":9509,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9503\/revisions\/9509"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=9503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=9503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=9503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}