
{"id":9353,"date":"2011-10-04T14:21:06","date_gmt":"2011-10-04T17:21:06","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=9353"},"modified":"2011-10-05T20:23:34","modified_gmt":"2011-10-05T23:23:34","slug":"virginia-hagge-e-nomeada-superintendente-federal-da-agricultura-na-bahia","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/04\/virginia-hagge-e-nomeada-superintendente-federal-da-agricultura-na-bahia\/","title":{"rendered":"VIRGINIA HAGGE \u00c9 NOMEADA SUPERINTENDENTE FEDERAL DA AGRICULTURA NA BAHIA"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" src=\"http:\/\/www.blogdaresenhageral.com.br\/v1\/wp-content\/uploads\/virginia-jacy.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Ex-deputada deve assumir o cargo nos pr\u00f3ximos dias<\/em><\/strong><\/p>\n<p>A ex-deputada estadual Virginia Hagge foi nomeada para exercer o cargo em comiss\u00e3o de Superintendente Federal, c\u00f3digo DAS 101.4, da Superintend\u00eancia Federal de Agricultura, Pecu\u00e1ria e Abastecimento no Estado da Bahia. A nomea\u00e7\u00e3o de Virginia foi publicada no Di\u00e1rio Oficial da Uni\u00e3o desta segunda-feira, pegando todos de surpresa, inclusive seus correligion\u00e1rios do PMDB de Itapetinga. Ningu\u00e9m soube informar se a nomea\u00e7\u00e3o da ex-deputada foi pela cota de Geddel ou do pr\u00f3prio Wagner, com quem a fam\u00edlia Hagge nutre uma grande amizade.<\/p>\n<p style=\"text-align: left;\"><strong><em>Por DAVI FERRAZ<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex-deputada deve assumir o cargo nos pr\u00f3ximos dias A ex-deputada estadual Virginia Hagge foi nomeada para exercer o cargo em comiss\u00e3o de Superintendente Federal, c\u00f3digo DAS 101.4, da Superintend\u00eancia Federal de Agricultura, Pecu\u00e1ria e Abastecimento no Estado da Bahia. A nomea\u00e7\u00e3o de Virginia foi publicada no Di\u00e1rio Oficial da Uni\u00e3o desta segunda-feira, pegando todos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-9353","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1331,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=9353"}],"version-history":[{"count":5,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9353\/revisions"}],"predecessor-version":[{"id":9357,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9353\/revisions\/9357"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=9353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=9353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=9353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}