
{"id":9280,"date":"2011-10-02T10:56:18","date_gmt":"2011-10-02T13:56:18","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=9280"},"modified":"2011-10-03T00:13:57","modified_gmt":"2011-10-03T03:13:57","slug":"o-q-da-questao","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/02\/o-q-da-questao\/","title":{"rendered":"O &#8216;Q&#8217; DA QUEST\u00c3O"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.humordaterra.com\/wp-content\/uploads\/2010\/08\/minha-casa.jpg\" alt=\"\" width=\"500\" \/><\/p>\n<p>ITAPETINGA: Muita gente fica a se perguntar por que tanta disputa por uma secretaria sem muitos recursos, como a do Desenvolvimento Social. Os programas, dizem alguns, s\u00e3o quase todos do governo federal e as verbas s\u00e3o carimbadas. Ser\u00e1 que isto d\u00e1 votos? E por a\u00ed vai&#8230;<\/p>\n<p>Na verdade, se dependesse dos programas assistenciais da Secretaria do Desenvolvimento Social, n\u00e3o daria sequer para eleger um vereador, mas h\u00e1 outro fator que algumas pessoas desavisadas n\u00e3o est\u00e3o levando em conta e que \u00e9 o real motivo de toda a cobi\u00e7a pelo comando da Secretaria do Desenvolvimento Social: as 500 casas do programa &#8216;Minha Casa Minha Vida&#8217;, que est\u00e3o sendo constru\u00eddas no &#8220;Piab\u00e3o&#8221;. \u00c9 a\u00ed que mora a cobi\u00e7a e o perigo.<\/p>\n<p>N\u00e3o foi por outro motivo, podem ter certeza, que caiu a secret\u00e1ria Kelene (ou Cledilene) e que o PT de Marc\u00e3o n\u00e3o quer largar o osso. Na outra ponta, est\u00e3o os vereadores, assessores e correligion\u00e1rios fisiol\u00f3gicos do prefeito Z\u00e9 Carlos, do tipo <em>quero-quero<\/em>, <em>eu tamb\u00e9m quero<\/em>, <em>eu quero\u00a0o meu<\/em>, <em>eu\u00a0quero\u00a0um tiquinho<\/em>, <em>eu quero um Monte<\/em> e <em>queira Deus<\/em>, todos de olho nas casinhas que est\u00e3o sendo constru\u00eddas pelo Governo Federal e que podem render muitos votos e muita grana, se forem &#8216;partilhadas&#8217; como eles querem.<\/p>\n<p>N\u00e3o foi por outra raz\u00e3o que a primeir\u00edssima dama bateu de frente com a secret\u00e1ria Kelene, que resistiu at\u00e9 onde pode para n\u00e3o ceder \u00e0 press\u00e3o dos pol\u00edticos, todos de olho nas primeiras casas que foram entregues no Loteamento 12 de dezembro, tamb\u00e9m conhecido como &#8220;Brogod\u00f3&#8221;. Kelene acabou cedendo, mas cedeu pouco, para uma clientela de apetite voraz, que queria tudo. A futricada das madames do baixo escal\u00e3o foi apenas o instrumento utilizado pelo prefeito e pelo PT, para fritar e derrubar a secret\u00e1ria.<\/p>\n<p>Na pr\u00f3xima <em>sele\u00e7\u00e3o<\/em> dos <em>contemplados<\/em> para receberem as 500 casinhas do <em>Piab\u00e3o<\/em>, outra disputa ser\u00e1 travada, dessa vez entre as v\u00e1rias fac\u00e7\u00f5es que dominam o grupo do prefeito, cada uma querendo mais que a outra. Vai ser briga de foice no escuro, com direito a queda de secret\u00e1rio(a), chilique de madame, bate-boca na c\u00e2mara e nas r\u00e1dios, e muito mais.<\/p>\n<p>O &#8216;Q&#8217; da quest\u00e3o \u00e9 o &#8216;Q&#8217; do <em>quero<\/em>, ou melhor, do <em>queremos<\/em>. Vamos ver at\u00e9 onde ir\u00e1 essa pouca vergonha.<\/p>\n<p><em><strong>Por DAVI FERRAZ<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ITAPETINGA: Muita gente fica a se perguntar por que tanta disputa por uma secretaria sem muitos recursos, como a do Desenvolvimento Social. Os programas, dizem alguns, s\u00e3o quase todos do governo federal e as verbas s\u00e3o carimbadas. Ser\u00e1 que isto d\u00e1 votos? E por a\u00ed vai&#8230; Na verdade, se dependesse dos programas assistenciais da Secretaria [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-9280","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1514,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=9280"}],"version-history":[{"count":8,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9280\/revisions"}],"predecessor-version":[{"id":9283,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/9280\/revisions\/9283"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=9280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=9280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=9280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}