
{"id":13395,"date":"2012-03-03T10:17:47","date_gmt":"2012-03-03T13:17:47","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=13395"},"modified":"2012-03-03T10:17:47","modified_gmt":"2012-03-03T13:17:47","slug":"ilheus-ministerio-publico-pede-suspensao-da-lei-do-pai-nosso","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2012\/03\/03\/ilheus-ministerio-publico-pede-suspensao-da-lei-do-pai-nosso\/","title":{"rendered":"ILH\u00c9US: MINIST\u00c9RIO P\u00daBLICO PEDE SUSPENS\u00c3O DA LEI DO &#8216;PAI NOSSO&#8217;"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/revistabahia.com.br\/wp-content\/uploads\/2012\/02\/Alunos-rezando20121449.jpg\" alt=\"\" width=\"400\" \/><\/p>\n<p style=\"text-align: center;\"><em>Lei come\u00e7ou a ser aplicada nesta quinta-feira (01)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>ILH\u00c9US: A lei do &#8216;Pai Nosso&#8217;,\u00a0que obriga os estudantes da rede p\u00fablica de ensino de Ilh\u00e9us, cidade da regi\u00e3o sul da Bahia, a rezarem a ora\u00e7\u00e3o todos os dias antes das aulas, \u00e9 alvo de uma a\u00e7\u00e3o do Minist\u00e9rio P\u00fablico da Bahia (MP-BA), que pediu, nesta sexta-feira (2), a suspens\u00e3o da medida. A solicita\u00e7\u00e3o foi encaminhada ao Tribunal de Justi\u00e7a da Bahia em forma de uma A\u00e7\u00e3o Direta de Inconstitucionalidade (Adin) com pedido de liminar. O prefeito Newton Lima (PT) aprovou a lei no m\u00eas de dezembro do ano passado e a ordem \u00e9 aplicada desde o dia 13 de fevereiro, in\u00edcio do ano letivo. Na a\u00e7\u00e3o, o MP-BA classifica a lei, de n\u00famero 3.589\/2011, como &#8220;inconstitucional&#8221;. \u00a0O \u00f3rg\u00e3o considera que obrigar a pr\u00e1tica di\u00e1ria da ora\u00e7\u00e3o aos alunos &#8220;viola de modo expl\u00edcito normas das Constitui\u00e7\u00f5es Federal e Estadual por afrontar diretamente a liberdade de religi\u00e3o e culto&#8221;. A Adin foi assinada pelo procurador-geral de Justi\u00e7a Adjunto para Assuntos Jur\u00eddicos, R\u00f4mulo de Andrade Moreira, e o assessor especial da Procuradoria Geral de Justi\u00e7a, promotor de Justi\u00e7a Cristiano Chaves de Farias. Com informa\u00e7\u00f5es do G1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lei come\u00e7ou a ser aplicada nesta quinta-feira (01) &nbsp; ILH\u00c9US: A lei do &#8216;Pai Nosso&#8217;,\u00a0que obriga os estudantes da rede p\u00fablica de ensino de Ilh\u00e9us, cidade da regi\u00e3o sul da Bahia, a rezarem a ora\u00e7\u00e3o todos os dias antes das aulas, \u00e9 alvo de uma a\u00e7\u00e3o do Minist\u00e9rio P\u00fablico da Bahia (MP-BA), que pediu, nesta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-13395","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1264,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/13395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=13395"}],"version-history":[{"count":2,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/13395\/revisions"}],"predecessor-version":[{"id":13397,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/13395\/revisions\/13397"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=13395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=13395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=13395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}