
{"id":124894,"date":"2026-05-12T12:24:42","date_gmt":"2026-05-12T15:24:42","guid":{"rendered":"https:\/\/www.sudoestehoje.com.br\/novoportal\/?p=124894"},"modified":"2026-05-12T12:24:42","modified_gmt":"2026-05-12T15:24:42","slug":"onibus-da-cidade-sol-tomba-na-br-324-e-deixa-um-morto-e-feridos","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2026\/05\/12\/onibus-da-cidade-sol-tomba-na-br-324-e-deixa-um-morto-e-feridos\/","title":{"rendered":"\u00d4NIBUS DA CIDADE SOL TOMBA NA BR-324 E DEIXA UM MORTO E FERIDOS"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-124895\" src=\"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2026\/05\/IMG-20260512-WA0046.jpg\" alt=\"\" width=\"600\" height=\"360\" \/><\/p>\n<p>Um grave acidente envolvendo um \u00f4nibus da empresa Cidade Sol foi registrado na manh\u00e3 desta ter\u00e7a-feira (12), na BR-324, no trecho de Sim\u00f5es Filho, sentido Feira de Santana. De acordo com informa\u00e7\u00f5es iniciais, uma pessoa morreu ap\u00f3s o tombamento do coletivo.<\/p>\n<p>Segundo relatos preliminares, o \u00f4nibus seguia em dire\u00e7\u00e3o ao Polo Petroqu\u00edmico de Cama\u00e7ari quando o acidente aconteceu. Al\u00e9m da v\u00edtima fatal, outras quatro pessoas ficaram feridas e receberam atendimento das equipes de resgate acionadas para o local.<\/p>\n<p>Ainda n\u00e3o h\u00e1 confirma\u00e7\u00e3o oficial sobre as causas do acidente. No momento do tombamento, chovia na regi\u00e3o, o que pode ter contribu\u00eddo para a ocorr\u00eancia. O acidente aconteceu logo ap\u00f3s um posto da Pol\u00edcia Rodovi\u00e1ria Federal (PRF).<\/p>\n<p>Equipes da PRF, do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU) e do Corpo de Bombeiros estiveram no local prestando socorro \u00e0s v\u00edtimas e organizando o tr\u00e2nsito na rodovia, que apresentou lentid\u00e3o ap\u00f3s o ocorrido.<\/p>\n<p>As identidades das v\u00edtimas ainda n\u00e3o foram divulgadas oficialmente. O caso ser\u00e1 investigado pelas autoridades competentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grave acidente envolvendo um \u00f4nibus da empresa Cidade Sol foi registrado na manh\u00e3 desta ter\u00e7a-feira (12), na BR-324, no trecho de Sim\u00f5es Filho, sentido Feira de Santana. De acordo com informa\u00e7\u00f5es iniciais, uma pessoa morreu ap\u00f3s o tombamento do coletivo. Segundo relatos preliminares, o \u00f4nibus seguia em dire\u00e7\u00e3o ao Polo Petroqu\u00edmico de Cama\u00e7ari quando [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":124895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-124894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"views":227,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/124894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=124894"}],"version-history":[{"count":1,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/124894\/revisions"}],"predecessor-version":[{"id":124896,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/124894\/revisions\/124896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media\/124895"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=124894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=124894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=124894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}