
{"id":10166,"date":"2011-10-31T13:27:21","date_gmt":"2011-10-31T16:27:21","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=10166"},"modified":"2011-10-31T13:27:21","modified_gmt":"2011-10-31T16:27:21","slug":"cronica-de-itororo","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/31\/cronica-de-itororo\/","title":{"rendered":"CR\u00d4NICA DE ITOROR\u00d3"},"content":{"rendered":"<p><a href=\"http:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2011\/10\/CABE.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-10167\" title=\"CABE\" src=\"http:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2011\/10\/CABE-500x446.jpg\" alt=\"\" width=\"500\" height=\"446\" srcset=\"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2011\/10\/CABE-500x446.jpg 500w, https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2011\/10\/CABE-1024x914.jpg 1024w, https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-content\/uploads\/2011\/10\/CABE.jpg 1258w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Antes de Adroaldo tomar posse em 2008, conversando com ele (ele deve lembrar muito bem disso), eu disse que uma das coisas que ele poderia fazer para funcionar a transpar\u00eancia no governo, era ele convocar uma esp\u00e9cie de \u201cCONSELHO DOS CONTRAS\u201d para fiscalizar o governo a partir dali. Falei com outras pessoas mais pr\u00f3ximas tamb\u00e9m. O governo n\u00e3o dava nem \u201cthum\u201d para este man\u00e9 minha \u00e9gua, aqui.\u00a0\u00a0O tempo foi passando e comecei a notar que a minha ideia n\u00e3o se fazia presente, n\u00e3o tomava corpo, ao contr\u00e1rio ia caindo no esquecimento, eu fui me sentindo assim, um daqueles condecorados com a honrosa medalha dos exclu\u00eddos do governo e do clube dos amigos hist\u00f3ricos, pap\u00e9is foram instantaneamente invertidos. \u00c9 assim que come\u00e7a um bom governo, como um apetite voraz, animalesco, tipo alguns felinos ou aracn\u00eddeos, que na falta do que comer (que n\u00e3o era o caso), acabam devorando at\u00e9 os pr\u00f3prios filhos.<!--more--><\/p>\n<p>Ao presumi, que gozaria dos louros dessa amizade hist\u00f3rica, \u00e9pica, em sua conquista, no m\u00ednimo partilhando e fomentado ideias que fossem fazer o governo por n\u00f3s preconizado durante todo o tempo de luta, desde antes da funda\u00e7\u00e3o do PT, em minha oficina de serigrafia em fevereiro 1990. Adroaldo chegou para o PT, cabalisticamente 13 anos depois em 8 de fevereiro de 2003. Nunca imaginei que o governo revolucion\u00e1rio que\u00a0\u00a0se instalaria em Itoror\u00f3 com a minha modesta e particular\u00edssima colabora\u00e7\u00e3o, fosse me expelir de seu corpo, como um carneg\u00e3o ou um berne. Fui sumariamente boicotado nas minhas opini\u00f5es relacionadas ao in\u00edcio da administra\u00e7\u00e3o, especialmente pelo ilustr\u00edssimo amigo de mais de 30 anos e agora prefeito de Itoror\u00f3 que, diga-se de passagem, s\u00f3 se encontra onde est\u00e1 porque eu peitei o PT, que n\u00e3o o queria. (isso na elei\u00e7\u00e3o de 2004), Ele sabe muito bem disso, mas como \u00e9 omisso, astuto, covarde e maligno, n\u00e3o ir\u00e1 nunca fazer, de p\u00fablico, alus\u00e3o \u00e0 minha participa\u00e7\u00e3o em todo o processo, ao contr\u00e1rio, desqualificar o m\u00e1ximo que puder o soldado rebelde que partilhou durante mais de 20 anos as mesmas dores e as mesmas armas nas trincheiras opostas dos inimigos que ocupam hoje o seu governo, faz parte de seus planos para sua perman\u00eancia traidora da esperan\u00e7a que t\u00ednhamos nele. De l\u00e1 para c\u00e1, (2004, sem contar as anteriores), s\u00f3 eu sei a luta que travei para que ele chegasse a ocupar o cargo de prefeito na elei\u00e7\u00e3o seguinte, a de 2008, elei\u00e7\u00e3o ganha, miss\u00e3o cumprida, retornei para Itoror\u00f3 s\u00f3 para escrever poesia pintar e ser amigo do rei.\u00a0\u00a0\u00a0J\u00e1 no in\u00edcio chovia den\u00fancias de malversa\u00e7\u00e3o do dinheiro p\u00fablico que tomavam conta das ruas de Itoror\u00f3. Dirigi-me ao prefeito, cheio de dedos para falar (o homem agora era o prefeito), falei. Poucos dias depois o prefeito pedia a Rosemberg Pinto o deputado, para me tirar daqui que eu iria atrapalh\u00e1-lo em sua administra\u00e7\u00e3o. A partir dali, &#8211; Rompi de vez e come\u00e7ou o pobre escriba a peregrinar refor\u00e7os para sobreviver para questionar os passos transparentes em malignidade desse grande governo, o que me valem, hoje, algumas a\u00e7\u00f5es na justi\u00e7a impetradas pelo corpo advocat\u00edcio do governo. S\u00e3o tantos os advogados que a nossa prefeitura parece mais com aqueles escrit\u00f3rios da avenida paulista ou de Wall Street, com especialistas saindo pelo ladr\u00e3o ou pela torneira, em todas as \u00e1reas do governo, cada vez mais se parecendo menos com prefeitura.\u00a0\u00a0Certamente para se defender da possibilidade de a\u00e7\u00e3o por parte dos advers\u00e1rios que viessem apontar ou reagir ao excesso de irregularidades do governo. Hoje percebo que estou errado, muito errado, entendendo o porqu\u00ea do prefeito considera leg\u00edtimas as a\u00e7\u00f5es contra esse escribazinho aqui. COMO EU SOU BURRO!!!\u00a0\u00a0Ao inv\u00e9s de formar um conselho dos contras, sugerido por mim, o prefeito foi r\u00e1pido no gatilho, montou logo sua equipe com todos os contras que n\u00f3s vencemos nas elei\u00e7\u00f5es daquele ano, com isso n\u00e3o s\u00f3 aderia \u00e0 minha ideia, como tamb\u00e9m fechava as porteiras da corrup\u00e7\u00e3o, do desmantelo, do desperd\u00edcio p\u00fablico e outras mazelas mais&#8230; O senhor prefeito n\u00e3o \u00e9 besta n\u00e3o. Saiu na frente e, o burro aqui, n\u00e3o entendendo nada, foi ca\u00e7ar briga com essa intelig\u00eancia internacional. Por conta disso tudo, a vida em Itoror\u00f3 \u00e9 maravilhosa!\u00a0\u00a0Bem verdade que existe um grande \u00edndice de suic\u00eddios, que est\u00e3o diretamente ligados ao excesso de vida com abundancia, contracenando com o suic\u00eddio da moral, da \u00e9tica, da liberdade de express\u00e3o e principalmente o suic\u00eddio coletivo dos valores crist\u00e3os, que hoje em dia, poucos professam. Mas isso \u00e9 fichinha, quem ainda se importa com isso? Tudo que acontece em Itoror\u00f3, se deve em parte \u00e0 heran\u00e7a dos gestores anteriores e \u00e0 incomensur\u00e1vel bondade do prefeito Adroaldo com suas pol\u00edticas p\u00fablicas de primeira qualidade. Aqui o povo n\u00e3o passa raiva nem fome. O t\u00e9dio, (\u00fanica causa mortis) \u00e9 um dos nossos bens preciosos na arte de bem morrer, e que fazemos quest\u00e3o de preserv\u00e1-lo, aqui. T\u00e9dio porque o governo do PT de Adroaldo supre com folga as oito exig\u00eancias da ONU: 1) Acabou com a mis\u00e9ria e a fome, 2) Educa\u00e7\u00e3o B\u00e1sica de qualidade para todos, 3) Igualdade entre sexos e valoriza\u00e7\u00e3o da mulher, 4) Melhorou a sa\u00fade das gestantes, 5) Combateu a AIDS como ningu\u00e9m e erradicou todos os focos de doen\u00e7as. Aqui se o cidad\u00e3o espirrar, o SAMU, est\u00e1 em cima \u201cdo cabra\u201d.\u00a0\u00a0Sa\u00fade, meu irm\u00e3ozinho! M\u00e9dico particular aqui morre de fome.\u00a0\u00a06) N\u00e3o temos mortalidade infantil, 7) Qualidade de vida e respeito ao meio ambiente \u00e9 dez. 8) Todos trabalham em prol do desenvolvimento da cidade. Portanto, pelas minhas cr\u00edticas ao governo maravilhoso do prefeito Adroaldo. Rendo \u2013 me a esse governo perfeito e justo, junto, rendo minhas desculpas sortidas de homenagens a esta cidade modelo de gest\u00e3o. O problema mesmo aqui, \u00e9 o t\u00e9dio de se ter tantas coisas boas, mas o prefeito j\u00e1 detectou o problema e logo vai resolver, piorando algumas a\u00e7\u00f5es para melhorar ainda mais a vida de quem n\u00e3o precisa. Principalmente, a vida dos contras de quem esse governo desgovernado no seu \u201cmodus operandi\u201d est\u00e1 fazendo barba e cabelo, diante dos cofres do sal\u00e3o do tesouro p\u00fablico municipal. Ah, se arrependimento matasse&#8230;<\/p>\n<p><em><strong>Por MILTON MARINHO<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de Adroaldo tomar posse em 2008, conversando com ele (ele deve lembrar muito bem disso), eu disse que uma das coisas que ele poderia fazer para funcionar a transpar\u00eancia no governo, era ele convocar uma esp\u00e9cie de \u201cCONSELHO DOS CONTRAS\u201d para fiscalizar o governo a partir dali. Falei com outras pessoas mais pr\u00f3ximas tamb\u00e9m. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-10166","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1457,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=10166"}],"version-history":[{"count":3,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10166\/revisions"}],"predecessor-version":[{"id":10170,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10166\/revisions\/10170"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=10166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=10166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=10166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}