
{"id":10039,"date":"2011-10-27T23:01:31","date_gmt":"2011-10-28T02:01:31","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=10039"},"modified":"2011-10-28T12:16:21","modified_gmt":"2011-10-28T15:16:21","slug":"michel-hagge-sofre-acidente-e-e-internado-em-vitoria-da-conquista","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/27\/michel-hagge-sofre-acidente-e-e-internado-em-vitoria-da-conquista\/","title":{"rendered":"MICHEL HAGGE SOFRE ACIDENTE E \u00c9 INTERNADO EM VIT\u00d3RIA DA CONQUISTA"},"content":{"rendered":"<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.politicosdosuldabahia.com.br\/v1\/wp-content\/uploads\/michel-hagge-itapetinga-brumadonoticias-300x225.jpg\" alt=\"\" width=\"400\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Michel Hagge foi internado no Samur, com suspeita de fratura na bacia<\/strong><\/em><\/p>\n<p>Nesta quinta-feira, o ex-prefeito de Itapetinga, Michel Hagge (PMDB), sofreu um acidente em sua fazenda, no munic\u00edpio de Nova Cana\u00e3, e acabou fraturando a bacia. O pol\u00edtico foi internado no hospital Samur em Vit\u00f3ria da Conquista.\u00a0Michel tem 84 anos de idade e foi deputado estadual e prefeito por tr\u00eas vezes de Itapetinga. Ele n\u00e3o corre risco de vida, mas em fun\u00e7\u00e3o da fratura ficar\u00e1 algum tempo sem poder andar.\u00a0Segundo informa\u00e7\u00f5es da ex vice-prefeita K\u00e1tia Espinheira e amigos do ex-prefeito, o acidente aconteceu quando ele estava cavalgando. Com informa\u00e7\u00f5es do\u00a0<em>Pol\u00edticos do Sul da Bahia<\/em><\/p>\n<p>\u00daLTIMAS INFORMA\u00c7\u00d5ES<\/p>\n<p>Na manh\u00e3 desta quinta-feira, mantivemos contato com diversos amigos e parentes do ex-prefeito Michel Hagge, que nos informaram que a not\u00edcia de que ele teria fraturado a bacia n\u00e3o \u00e9 verdadeira. Na verdade, Michel se machucou enquanto cavalgava, mas n\u00e3o houve nenhuma fratura. Ele se recupera no hospital Samur, em Vit\u00f3ria da Conquista, e j\u00e1 falou ao telefone com diversos amigos.<\/p>\n<p><em><strong>Da Rada\u00e7\u00e3o<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Michel Hagge foi internado no Samur, com suspeita de fratura na bacia Nesta quinta-feira, o ex-prefeito de Itapetinga, Michel Hagge (PMDB), sofreu um acidente em sua fazenda, no munic\u00edpio de Nova Cana\u00e3, e acabou fraturando a bacia. O pol\u00edtico foi internado no hospital Samur em Vit\u00f3ria da Conquista.\u00a0Michel tem 84 anos de idade e foi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-10039","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1073,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=10039"}],"version-history":[{"count":5,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10039\/revisions"}],"predecessor-version":[{"id":10043,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10039\/revisions\/10043"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=10039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=10039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=10039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}