
{"id":10005,"date":"2011-10-27T18:55:56","date_gmt":"2011-10-27T21:55:56","guid":{"rendered":"http:\/\/www.sudoestehoje.com.br\/novoportal\/?p=10005"},"modified":"2011-10-27T18:55:56","modified_gmt":"2011-10-27T21:55:56","slug":"iguai-prefeito-abusa-de-diarias-e-e-multado-pelo-tcm","status":"publish","type":"post","link":"https:\/\/www.sudoestehoje.com.br\/novoportal\/2011\/10\/27\/iguai-prefeito-abusa-de-diarias-e-e-multado-pelo-tcm\/","title":{"rendered":"IGUA\u00cd: PREFEITO ABUSA DE DI\u00c1RIAS E \u00c9 MULTADO PELO TCM"},"content":{"rendered":"<div style=\"text-align: center;\"><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-wNFF8R972Y8\/TqhVzBn63CI\/AAAAAAAAATQ\/yEQkIVgBX84\/s1600\/images.jpg\" alt=\"\" width=\"300\" \/><\/div>\n<div style=\"text-align: center;\"><em><strong>Prefeito Ronaldo Moitinho pagou a ele pr\u00f3prio R$45 mil de di\u00e1rias<\/strong><\/em><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>O Tribunal de Contas dos Munic\u00edpios, na sess\u00e3o desta  ter\u00e7a-feira (25\/10), julgou procedente o termo de ocorr\u00eancia lavrado contra o  prefeito de Igua\u00ed, Ronaldo Moitinho dos Santos, em raz\u00e3o de pagamentos de  di\u00e1rias em valores irrazo\u00e1veis a si mesmo, no exerc\u00edcio de 2011.<\/div>\n<p><a rel=\"nofollow\" name=\"more\"><\/a><\/p>\n<div>\nO relator, conselheiro Jos\u00e9 Alfredo Rocha Dias,  imputou multa ao gestor no valor de R$ 5 mil e, em face da reincid\u00eancia revelada  e do descumprimento de determina\u00e7\u00e3o deste Tribunal, determinou a formula\u00e7\u00e3o de  representa\u00e7\u00e3o ao Minist\u00e9rio P\u00fablico. Cabe recurso da decis\u00e3o.<\/p>\n<p>Quando da  an\u00e1lise da documenta\u00e7\u00e3o de receita e despesa do Executivo, dos meses de janeiro  a junho, foram constadas a realiza\u00e7\u00e3o de pagamento de di\u00e1rias ao prefeito em  valores irrazo\u00e1veis, percebendo, no per\u00edodo citado, o montante de R$ 45 mil,  valor bem acima do seu sal\u00e1rio.<\/p>\n<p>A relatoria entendeu que o gestor,  reincidente e revel, revelou-se ganancioso no recebimento do dinheiro p\u00fablico,  esquecendo-se que a sua aplica\u00e7\u00e3o deve, prioritariamente, atender ao interesse  p\u00fablico, e n\u00e3o ao seu, particular.<\/p>\n<p>Definiu ainda que a Lei Municipal n\u00ba  126 de 04 de dezembro de 2008, ao estabelecer valores elevados para a referida  verba indenizat\u00f3ria, agride os princ\u00edpios constitucionais regedores da  Administra\u00e7\u00e3o P\u00fablica, da legitimidade, moralidade, economicidade e  razoabilidade.<\/p><\/div>\n<div><\/div>\n<div><em><strong>Blog Igua\u00ed Santos<\/strong><\/em><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prefeito Ronaldo Moitinho pagou a ele pr\u00f3prio R$45 mil de di\u00e1rias O Tribunal de Contas dos Munic\u00edpios, na sess\u00e3o desta ter\u00e7a-feira (25\/10), julgou procedente o termo de ocorr\u00eancia lavrado contra o prefeito de Igua\u00ed, Ronaldo Moitinho dos Santos, em raz\u00e3o de pagamentos de di\u00e1rias em valores irrazo\u00e1veis a si mesmo, no exerc\u00edcio de 2011. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"class_list":["post-10005","post","type-post","status-publish","format-standard","hentry","category-geral"],"views":1224,"_links":{"self":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/comments?post=10005"}],"version-history":[{"count":3,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10005\/revisions"}],"predecessor-version":[{"id":10008,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/posts\/10005\/revisions\/10008"}],"wp:attachment":[{"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/media?parent=10005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/categories?post=10005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sudoestehoje.com.br\/novoportal\/wp-json\/wp\/v2\/tags?post=10005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}